{"id":1142,"date":"2023-06-19T13:28:03","date_gmt":"2023-06-19T11:28:03","guid":{"rendered":"https:\/\/ysales.meetchum.be\/services\/"},"modified":"2023-06-28T00:11:29","modified_gmt":"2023-06-27T22:11:29","slug":"nos-services","status":"publish","type":"page","link":"https:\/\/y-sales.com\/fr\/nos-services\/","title":{"rendered":"NOS SERVICES"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1142\" class=\"elementor elementor-1142 elementor-694\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6536f92 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6536f92\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6837fe\" data-id=\"f6837fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac0b83 animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"8ac0b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"800\" src=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg\" class=\"attachment-full size-full wp-image-990\" alt=\"\" srcset=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg 1920w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-500x208.jpg 500w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-1200x500.jpg 1200w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-300x125.jpg 300w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-768x320.jpg 768w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-1536x640.jpg 1536w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-150x63.jpg 150w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader-480x200.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64b29a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64b29a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d34344\" data-id=\"1d34344\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-024fe0f elementor-widget elementor-widget-text-editor\" data-id=\"024fe0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos services<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-610954f\" data-id=\"610954f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aa43e3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4aa43e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-617e935\" data-id=\"617e935\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4bde90c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bde90c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0fe80c8\" data-id=\"0fe80c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a98ac14 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a98ac14\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2.jpg\" class=\"attachment-large size-large wp-image-1000\" alt=\"\" srcset=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2.jpg 1200w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2-500x334.jpg 500w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2-300x200.jpg 300w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2-768x513.jpg 768w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2-112x75.jpg 112w, https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Services2-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0501ce5\" data-id=\"0501ce5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bce9a7d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"bce9a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Y. Parce que nous avons la solution de vente pour votre projet de construction neuve.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cba4cd elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1cba4cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Y, c\u2019est un concept tr\u00e8s simple : nous vous aidons \u00e0 vendre efficacement vos projets de construction neuve. Pour ce faire, nous commen\u00e7ons par d\u00e9nicher le vendeur id\u00e9al pour votre projet. Mais notre mission est loin de s\u2019arr\u00eater l\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d5bc05 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d5bc05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54ce4a0\" data-id=\"54ce4a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6af2dfb animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6af2dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En quoi vous sommes-nous pr\u00e9cieux ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f40a04b elementor-widget elementor-widget-text-editor\" data-id=\"f40a04b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous vous aidons \u00e0 boucler plus rapidement et plus efficacement la vente de votre projet de construction neuve. Gr\u00e2ce \u00e0 un savant m\u00e9lange de techniques de vente et de marketing, nous vous offrons une <strong>approche de vente et de marketing int\u00e9grale <\/strong>: branding, planning m\u00e9dia et g\u00e9n\u00e9ration de leads, <strong>externalisation des ventes<\/strong> et gestion des bons professionnels de la vente. <em>Sales &amp; Marketing as a Service<\/em><strong>\u00a0: <\/strong>un service enti\u00e8rement d\u00e9di\u00e9 \u00e0 votre prosp\u00e9rit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51b5e61 elementor-widget elementor-widget-text-editor\" data-id=\"51b5e61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol>\n<li>Les solutions commerciales d\u2019Y<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f0c51da elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0c51da\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e5790a8\" data-id=\"e5790a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37e9ae4 elementor-widget elementor-widget-text-editor\" data-id=\"37e9ae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Recrutement et externalisation<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc17483 elementor-widget elementor-widget-text-editor\" data-id=\"cc17483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La vente est un m\u00e9tier en soi. H\u00e9las, elle ne fait pas encore l\u2019objet d\u2019un cursus d\u2019\u00e9tudes. Ce n\u2019est donc pas \u00e9tonnant de voir tant d\u2019entreprises peiner \u00e0 trouver les bons profils commerciaux. Heureusement, nous sommes l\u00e0 pour y rem\u00e9dier, car Y a fait du <strong>recrutement et de l\u2019externalisation des ventes<\/strong> son c\u0153ur de m\u00e9tier. Nous d\u00e9nichons les bonnes personnes pour d\u00e9charger nos clients du processus de vente. Nous associons les bons talents de notre \u00e9quipe de vente au bon projet afin de d\u00e9crocher les meilleurs r\u00e9sultats de vente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0543e9f\" data-id=\"0543e9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-758a157 elementor-widget elementor-widget-text-editor\" data-id=\"758a157\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gestion des \u00e9quipes de vente<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc305b5 elementor-widget elementor-widget-text-editor\" data-id=\"dc305b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019organisation d\u2019une op\u00e9ration de vente performante n\u2019est pas une mission facile. Chez Y, nous disposons de l\u2019exp\u00e9rience, des m\u00e9thodes et de l\u2019expertise indispensables pour constituer et g\u00e9rer des \u00e9quipes de vente bien huil\u00e9es et concentr\u00e9es sur un seul objectif clair\u00a0: d\u00e9crocher <strong>les meilleurs r\u00e9sultats de vente<\/strong>. Nous vous d\u00e9chargeons totalement des tracas de la vente et de la gestion de l\u2019\u00e9quipe commerciale pour que vous n\u2019ayez plus \u00e0 vous en soucier et que vous puissiez vous concentrer sur votre activit\u00e9 pr\u00e9f\u00e9r\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebd82c8 animated-slow elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ebd82c8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7daa049\" data-id=\"7daa049\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3bf30e elementor-widget elementor-widget-text-editor\" data-id=\"e3bf30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Formation &amp; recyclage dans la vente<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32f0355 elementor-widget elementor-widget-text-editor\" data-id=\"32f0355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Y, nous sommes par ailleurs convaincus que <strong>la formation constitue la cl\u00e9 du succ\u00e8s<\/strong>. Le talent seul ne suffit pas. D\u00e9nicher le bon profil n\u2019est pas toujours suffisant pour mener \u00e0 bien la vente (int\u00e9grale) d\u2019un projet. C\u2019est pourquoi nous dispensons nous-m\u00eames des <strong>formations commerciales intensives<\/strong> \u00e0 nos collaborateurs. Nos professionnels respectent un <strong>processus de vente standardis\u00e9 qui a fait ses preuves<\/strong>.<\/p>\n<p>Cette formation s\u2019articule globalement comme suit :<\/p>\n<ol>\n<li><u>Formation intensive<\/u> (3 mois) : processus de vente, techniques, connaissance du produit, outils, \u2026<\/li>\n<li><u>Trajectoire d\u2019accompagnement<\/u> (min. 18 mois) : suivi quotidien, coaching hebdomadaire, r\u00e9unions commerciales, coaching fr\u00e9quent sur le terrain<\/li>\n<li><u>Trajectoire de suivi <\/u>: r\u00e9unions de vente et de suivi hebdomadaires, coachings de terrain occasionnels<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0166a7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0166a7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b6436a\" data-id=\"5b6436a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64a1f2d elementor-widget elementor-widget-text-editor\" data-id=\"64a1f2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2. Les solutions marketing d\u2019Y<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea64efd elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea64efd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c4aad49\" data-id=\"c4aad49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45ae172 elementor-widget elementor-widget-text-editor\" data-id=\"45ae172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chaque projet de vente commence par la premi\u00e8re image ou la premi\u00e8re lettre que le client potentiel visualise. C\u2019est pourquoi nous faisons un pas en arri\u00e8re au d\u00e9part de chaque trajectoire de vente. Quelle est notre cible ? Quel est son besoin ? Et quel dispositif mettre en place pour y r\u00e9pondre ? Avant de proc\u00e9der \u00e0 la vente d\u2019un produit, nous mettons d\u2019abord au point notre arsenal de communication. Nous cr\u00e9ons une forte identit\u00e9 de marque (visuelle) et un plan m\u00e9dia approfondi, nous \u00e9laborons du mat\u00e9riel de marketing inspirant, nous mettons sur pied des campagnes marketing strat\u00e9giques et orient\u00e9es r\u00e9sultat ainsi que des campagnes efficaces pour g\u00e9n\u00e9rer des leads. Bref, <strong>nous mettons tout en \u0153uvre pour que notre \u00e9quipe de vente ait tous les outils en mains pour conqu\u00e9rir le march\u00e9 avec succ\u00e8s.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a25a73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a25a73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1af91ce\" data-id=\"1af91ce\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c45cbbd elementor-invisible elementor-widget elementor-widget-image\" data-id=\"c45cbbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/design.svg\" class=\"attachment-large size-large wp-image-1002\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71421b2 elementor-widget elementor-widget-text-editor\" data-id=\"71421b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>g\u00e9n\u00e9ration de leads<\/p>\n<p>rendu 3D<\/p>\n<p>site web<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e682f67\" data-id=\"e682f67\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fa4099 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6fa4099\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/plannen.svg\" class=\"attachment-large size-large wp-image-1004\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5c30d8 elementor-widget elementor-widget-text-editor\" data-id=\"f5c30d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>planning\u00a0m\u00e9dia<\/p>\n<p>brochures<\/p>\n<p>projets de vente<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-91dd9d7\" data-id=\"91dd9d7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34e0666 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"34e0666\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/Brnad.svg\" class=\"attachment-large size-large wp-image-1006\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb310ab elementor-widget elementor-widget-text-editor\" data-id=\"fb310ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Identit\u00e9 de marque &amp; logo<\/p>\n<p>strat\u00e9gie marketing<\/p>\n<p>\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8378981 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8378981\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a11d0a elementor-invisible\" data-id=\"2a11d0a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c9cf5c elementor-widget elementor-widget-text-editor\" data-id=\"5c9cf5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Besoin d\u2019une approche commerciale \u00e9prouv\u00e9e et efficace ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef98e68 elementor-widget elementor-widget-text-editor\" data-id=\"ef98e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous \u00eates \u00e0 la recherche de la bonne \u00e9quipe de vente pour atteindre vos objectifs le plus rapidement possible ? Voici votre ligne directe : appelez Nicolas Laporta au<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3158e4 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e3158e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"tel:0032497347734\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+32 497 34 77 34<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nos services Y. Parce que nous avons la solution de vente pour votre projet de construction neuve. Y, c\u2019est un concept tr\u00e8s simple : nous vous<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1142","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Y. Sales &amp; Marketing as a Service.<\/title>\n<meta name=\"description\" content=\"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/y-sales.com\/fr\/nos-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Y. Sales &amp; Marketing as a Service.\" \/>\n<meta property=\"og:description\" content=\"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/y-sales.com\/fr\/nos-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Y Sales\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-27T22:11:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/\",\"url\":\"https:\/\/y-sales.com\/fr\/nos-services\/\",\"name\":\"Y. Sales & Marketing as a Service.\",\"isPartOf\":{\"@id\":\"https:\/\/y-sales.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg\",\"datePublished\":\"2023-06-19T11:28:03+00:00\",\"dateModified\":\"2023-06-27T22:11:29+00:00\",\"description\":\"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.\",\"breadcrumb\":{\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/y-sales.com\/fr\/nos-services\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage\",\"url\":\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg\",\"contentUrl\":\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/y-sales.com\/fr\/nos-services\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/y-sales.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOS SERVICES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/y-sales.com\/#website\",\"url\":\"https:\/\/y-sales.com\/\",\"name\":\"Y Sales - It's all about the people that buy your products. Not the way around.\",\"description\":\"Omdat verkopen in de eerste plaats om mensen draait. That\u2019s Y!\",\"publisher\":{\"@id\":\"https:\/\/y-sales.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/y-sales.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/y-sales.com\/#organization\",\"name\":\"Y Sales - It's all about the people that buy your products. Not the way around.\",\"url\":\"https:\/\/y-sales.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/y-sales.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/favicon.jpg\",\"contentUrl\":\"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Y Sales - It's all about the people that buy your products. Not the way around.\"},\"image\":{\"@id\":\"https:\/\/y-sales.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Y. Sales & Marketing as a Service.","description":"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/y-sales.com\/fr\/nos-services\/","og_locale":"fr_FR","og_type":"article","og_title":"Y. Sales & Marketing as a Service.","og_description":"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.","og_url":"https:\/\/y-sales.com\/fr\/nos-services\/","og_site_name":"Y Sales","article_modified_time":"2023-06-27T22:11:29+00:00","og_image":[{"url":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/y-sales.com\/fr\/nos-services\/","url":"https:\/\/y-sales.com\/fr\/nos-services\/","name":"Y. Sales & Marketing as a Service.","isPartOf":{"@id":"https:\/\/y-sales.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage"},"image":{"@id":"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage"},"thumbnailUrl":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg","datePublished":"2023-06-19T11:28:03+00:00","dateModified":"2023-06-27T22:11:29+00:00","description":"De l\u2019externalisation des ventes jusqu\u2019aux solutions marketing en passant par les campagnes de g\u00e9n\u00e9ration de leads : Y vous aide \u00e0 vendre plus vite et plus efficacement votre immobilier neuf.","breadcrumb":{"@id":"https:\/\/y-sales.com\/fr\/nos-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/y-sales.com\/fr\/nos-services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/y-sales.com\/fr\/nos-services\/#primaryimage","url":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg","contentUrl":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/ServicesHeader.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/y-sales.com\/fr\/nos-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/y-sales.com\/fr\/"},{"@type":"ListItem","position":2,"name":"NOS SERVICES"}]},{"@type":"WebSite","@id":"https:\/\/y-sales.com\/#website","url":"https:\/\/y-sales.com\/","name":"Y Sales - It's all about the people that buy your products. Not the way around.","description":"Omdat verkopen in de eerste plaats om mensen draait. That\u2019s Y!","publisher":{"@id":"https:\/\/y-sales.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/y-sales.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/y-sales.com\/#organization","name":"Y Sales - It's all about the people that buy your products. Not the way around.","url":"https:\/\/y-sales.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/y-sales.com\/#\/schema\/logo\/image\/","url":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/favicon.jpg","contentUrl":"https:\/\/y-sales.com\/wp-content\/uploads\/2023\/06\/favicon.jpg","width":512,"height":512,"caption":"Y Sales - It's all about the people that buy your products. Not the way around."},"image":{"@id":"https:\/\/y-sales.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/pages\/1142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/comments?post=1142"}],"version-history":[{"count":14,"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/pages\/1142\/revisions"}],"predecessor-version":[{"id":1378,"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/pages\/1142\/revisions\/1378"}],"wp:attachment":[{"href":"https:\/\/y-sales.com\/fr\/wp-json\/wp\/v2\/media?parent=1142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}